{"id":2486,"date":"2024-09-12T08:00:50","date_gmt":"2024-09-12T06:00:50","guid":{"rendered":"https:\/\/www.elle.lu\/fr\/?p=2486"},"modified":"2024-11-03T09:02:27","modified_gmt":"2024-11-03T08:02:27","slug":"escalade-un-sport-qui-monte","status":"publish","type":"post","link":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html","title":{"rendered":"L&#8217;escalade : un sport qui monte"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"C\u2019est tendance, vous en avez forc\u00e9ment entendu parler, sur les r\u00e9seaux sociaux ou pendant les Jeux Olympiques de Paris 2024. ...","protected":false},"author":22,"featured_media":2487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4,11],"tags":[],"class_list":["post-2486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifestyle","category-sante"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;escalade : un sport qui monte - ELLE.lu Luxembourg<\/title>\n<meta name=\"description\" content=\"En salle ou en ext\u00e9rieur, l\u2019escalade compte de plus en plus d\u2019adeptes. Pr\u00e9sentation, bienfaits, lieux o\u00f9 pratiquer la grimpe au Luxembourg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;escalade : un sport qui monte - ELLE.lu Luxembourg\" \/>\n<meta property=\"og:description\" content=\"En salle ou en ext\u00e9rieur, l\u2019escalade compte de plus en plus d\u2019adeptes. Pr\u00e9sentation, bienfaits, lieux o\u00f9 pratiquer la grimpe au Luxembourg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html\" \/>\n<meta property=\"og:site_name\" content=\"ELLE.lu Luxembourg\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-12T06:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-03T08:02:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elle.lu\/fr\/wp-content\/uploads\/2024\/09\/unsplash-climbing-credits-x-902x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"902\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Am\u00e9lie Viel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Am\u00e9lie Viel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html\"},\"author\":{\"name\":\"Am\u00e9lie Viel\",\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/#\\\/schema\\\/person\\\/d8e58272c652d7b5585c18e680540e1a\"},\"headline\":\"L&#8217;escalade : un sport qui monte\",\"datePublished\":\"2024-09-12T06:00:50+00:00\",\"dateModified\":\"2024-11-03T08:02:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html\"},\"wordCount\":626,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/unsplash-climbing-credits-x.png\",\"articleSection\":[\"Lifestyle\",\"Sant\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html\",\"url\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html\",\"name\":\"L'escalade : un sport qui monte - ELLE.lu Luxembourg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/unsplash-climbing-credits-x.png\",\"datePublished\":\"2024-09-12T06:00:50+00:00\",\"dateModified\":\"2024-11-03T08:02:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/#\\\/schema\\\/person\\\/d8e58272c652d7b5585c18e680540e1a\"},\"description\":\"En salle ou en ext\u00e9rieur, l\u2019escalade compte de plus en plus d\u2019adeptes. Pr\u00e9sentation, bienfaits, lieux o\u00f9 pratiquer la grimpe au Luxembourg.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html#primaryimage\",\"url\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/unsplash-climbing-credits-x.png\",\"contentUrl\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/unsplash-climbing-credits-x.png\",\"width\":1814,\"height\":2060,\"caption\":\"\u00a9 Unsplash \\\/ x)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/2486-escalade-un-sport-qui-monte.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.elle.lu\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;escalade : un sport qui monte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/\",\"name\":\"ELLE.lu\",\"description\":\"Explorez les derni\u00e8res tendances mode, beaut\u00e9 et art de vivre au Luxembourg sur ELLE.lu. Un contenu exclusivement luxembourgeois sur notre site, r\u00e9seaux sociaux et YouTube.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/#\\\/schema\\\/person\\\/d8e58272c652d7b5585c18e680540e1a\",\"name\":\"Am\u00e9lie Viel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9741e9c258430d1c256463230ffaa49331981030725fd18fbb7eb78faca6a840?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9741e9c258430d1c256463230ffaa49331981030725fd18fbb7eb78faca6a840?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9741e9c258430d1c256463230ffaa49331981030725fd18fbb7eb78faca6a840?s=96&d=mm&r=g\",\"caption\":\"Am\u00e9lie Viel\"},\"url\":\"https:\\\/\\\/www.elle.lu\\\/fr\\\/author\\\/amelie-viel\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'escalade : un sport qui monte - ELLE.lu Luxembourg","description":"En salle ou en ext\u00e9rieur, l\u2019escalade compte de plus en plus d\u2019adeptes. Pr\u00e9sentation, bienfaits, lieux o\u00f9 pratiquer la grimpe au Luxembourg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html","og_locale":"fr_FR","og_type":"article","og_title":"L'escalade : un sport qui monte - ELLE.lu Luxembourg","og_description":"En salle ou en ext\u00e9rieur, l\u2019escalade compte de plus en plus d\u2019adeptes. Pr\u00e9sentation, bienfaits, lieux o\u00f9 pratiquer la grimpe au Luxembourg.","og_url":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html","og_site_name":"ELLE.lu Luxembourg","article_published_time":"2024-09-12T06:00:50+00:00","article_modified_time":"2024-11-03T08:02:27+00:00","og_image":[{"width":902,"height":1024,"url":"https:\/\/www.elle.lu\/fr\/wp-content\/uploads\/2024\/09\/unsplash-climbing-credits-x-902x1024.png","type":"image\/png"}],"author":"Am\u00e9lie Viel","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Am\u00e9lie Viel","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html#article","isPartOf":{"@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html"},"author":{"name":"Am\u00e9lie Viel","@id":"https:\/\/www.elle.lu\/fr\/#\/schema\/person\/d8e58272c652d7b5585c18e680540e1a"},"headline":"L&#8217;escalade : un sport qui monte","datePublished":"2024-09-12T06:00:50+00:00","dateModified":"2024-11-03T08:02:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html"},"wordCount":626,"commentCount":0,"image":{"@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html#primaryimage"},"thumbnailUrl":"https:\/\/www.elle.lu\/fr\/wp-content\/uploads\/2024\/09\/unsplash-climbing-credits-x.png","articleSection":["Lifestyle","Sant\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html","url":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html","name":"L'escalade : un sport qui monte - ELLE.lu Luxembourg","isPartOf":{"@id":"https:\/\/www.elle.lu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html#primaryimage"},"image":{"@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html#primaryimage"},"thumbnailUrl":"https:\/\/www.elle.lu\/fr\/wp-content\/uploads\/2024\/09\/unsplash-climbing-credits-x.png","datePublished":"2024-09-12T06:00:50+00:00","dateModified":"2024-11-03T08:02:27+00:00","author":{"@id":"https:\/\/www.elle.lu\/fr\/#\/schema\/person\/d8e58272c652d7b5585c18e680540e1a"},"description":"En salle ou en ext\u00e9rieur, l\u2019escalade compte de plus en plus d\u2019adeptes. Pr\u00e9sentation, bienfaits, lieux o\u00f9 pratiquer la grimpe au Luxembourg.","breadcrumb":{"@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html#primaryimage","url":"https:\/\/www.elle.lu\/fr\/wp-content\/uploads\/2024\/09\/unsplash-climbing-credits-x.png","contentUrl":"https:\/\/www.elle.lu\/fr\/wp-content\/uploads\/2024\/09\/unsplash-climbing-credits-x.png","width":1814,"height":2060,"caption":"\u00a9 Unsplash \/ x)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elle.lu\/fr\/2486-escalade-un-sport-qui-monte.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.elle.lu\/fr"},{"@type":"ListItem","position":2,"name":"L&#8217;escalade : un sport qui monte"}]},{"@type":"WebSite","@id":"https:\/\/www.elle.lu\/fr\/#website","url":"https:\/\/www.elle.lu\/fr\/","name":"ELLE.lu","description":"Explorez les derni\u00e8res tendances mode, beaut\u00e9 et art de vivre au Luxembourg sur ELLE.lu. Un contenu exclusivement luxembourgeois sur notre site, r\u00e9seaux sociaux et YouTube.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elle.lu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.elle.lu\/fr\/#\/schema\/person\/d8e58272c652d7b5585c18e680540e1a","name":"Am\u00e9lie Viel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9741e9c258430d1c256463230ffaa49331981030725fd18fbb7eb78faca6a840?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9741e9c258430d1c256463230ffaa49331981030725fd18fbb7eb78faca6a840?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9741e9c258430d1c256463230ffaa49331981030725fd18fbb7eb78faca6a840?s=96&d=mm&r=g","caption":"Am\u00e9lie Viel"},"url":"https:\/\/www.elle.lu\/fr\/author\/amelie-viel"}]}},"jetpack_featured_media_url":"https:\/\/www.elle.lu\/fr\/wp-content\/uploads\/2024\/09\/unsplash-climbing-credits-x.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/posts\/2486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/comments?post=2486"}],"version-history":[{"count":2,"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/posts\/2486\/revisions"}],"predecessor-version":[{"id":2489,"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/posts\/2486\/revisions\/2489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/media\/2487"}],"wp:attachment":[{"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/media?parent=2486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/categories?post=2486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elle.lu\/fr\/wp-json\/wp\/v2\/tags?post=2486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}